{"id":42817,"date":"2024-07-01T15:12:15","date_gmt":"2024-07-01T13:12:15","guid":{"rendered":"https:\/\/tridenstechnology.com\/?p=42817"},"modified":"2025-02-06T15:38:00","modified_gmt":"2025-02-06T13:38:00","slug":"plan-mobile-prepaye","status":"publish","type":"post","link":"https:\/\/tridenstechnology.com\/fr\/prepaid-mobile-plan\/","title":{"rendered":"Forfaits mobiles pr\u00e9pay\u00e9s : Comment fonctionnent-ils ?"},"content":{"rendered":"<p><strong><em>Environ un tiers des citoyens am\u00e9ricains (36%) disposent d'un plan de t\u00e9l\u00e9phonie mobile pr\u00e9pay\u00e9. Ils paient \u00e0 l'avance pour les donn\u00e9es et les minutes ou paient au fur et \u00e0 mesure et rechargent en fonction des besoins.<\/em><\/strong><\/p>\n\n\n\n<div class=\"wp-block-yoast-seo-table-of-contents yoast-table-of-contents\"><h2>Table des mati\u00e8res<\/h2><ul><li><a href=\"#h-what-is-a-prepaid-mobile-plan-amp-how-does-it-work\" data-level=\"2\">Qu'est-ce qu'un forfait mobile pr\u00e9pay\u00e9 et comment fonctionne-t-il ?<\/a><\/li><li><a href=\"#h-what-is-a-prepaid-mobile-phone\" data-level=\"2\">Qu'est-ce qu'un t\u00e9l\u00e9phone portable pr\u00e9pay\u00e9 ?<\/a><\/li><li><a href=\"#h-who-are-prepaid-mobile-plans-best-for\" data-level=\"2\">\u00c0 qui s'adressent les forfaits mobiles pr\u00e9pay\u00e9s ?<\/a><\/li><li><a href=\"#h-common-deals-and-offers\" data-level=\"2\">Offres courantes<\/a><\/li><li><a href=\"#h-market-analysis\" data-level=\"2\">Analyse du march\u00e9<\/a><\/li><li><a href=\"#h-how-prepaid-billing-works\" data-level=\"2\">Comment fonctionne la facturation pr\u00e9pay\u00e9e ?<\/a><\/li><\/ul><\/div>\n\n\n\n<p><em>Pr\u00e9pay\u00e9<\/em> est un terme de facturation pour <strong>le paiement \u00e0 l'avance.<\/strong><\/p>\n\n\n\n<p>Vous avez peut-\u00eatre entendu d'autres termes pour d\u00e9signer les plans de t\u00e9l\u00e9phonie mobile pr\u00e9pay\u00e9s, tels que \"pay-as-you-go\" (PAYG), \"pay-as-you-talk\", etc.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-what-is-a-prepaid-mobile-plan-amp-how-does-it-work\">Qu'est-ce qu'un forfait mobile pr\u00e9pay\u00e9 et comment fonctionne-t-il ?<\/h2>\n\n\n\n<p>Un plan mobile pr\u00e9pay\u00e9 est exactement ce qu'il semble \u00eatre : vous payez \u00e0 l'avance un montant fixe d'appels, de SMS et de donn\u00e9es.<\/p>\n\n\n\n<p>Une fois le paiement effectu\u00e9, vous pouvez utiliser les services mobiles qui vous ont \u00e9t\u00e9 attribu\u00e9s jusqu'\u00e0 ce que votre solde soit \u00e9puis\u00e9.<\/p>\n\n\n\n<p>Une fois la valeur totale \u00e9puis\u00e9e, vous ne pourrez plus passer d'appels, envoyer de SMS ou effectuer des actions n\u00e9cessitant des donn\u00e9es jusqu'\u00e0 ce que vous les rechargiez.<\/p>\n\n\n\n<p>Selon l'op\u00e9rateur, la quantit\u00e9 de services mobiles attribu\u00e9s peut expirer apr\u00e8s une certaine p\u00e9riode, le plus souvent apr\u00e8s 30 jours, mais il existe aussi des options d'une dur\u00e9e d'un an.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"300\" src=\"https:\/\/tridenstechnology.com\/wp-content\/uploads\/prepaid-billing-cycle.webp\" alt=\"Une infographie pr\u00e9sentant le cycle de facturation des forfaits mobiles pr\u00e9pay\u00e9s. Sur la gauche de l&#039;image, un calendrier vectoriel comporte une case coch\u00e9e pour le premier jour du mois. Sur la droite, le texte d\u00e9crit comment les forfaits mobiles pr\u00e9pay\u00e9s exigent un paiement \u00e0 l&#039;avance au d\u00e9but de chaque cycle de facturation.\" class=\"wp-image-42818\" srcset=\"https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/prepaid-billing-cycle.webp 1024w, https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/prepaid-billing-cycle-300x88.webp 300w, https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/prepaid-billing-cycle-768x225.webp 768w, https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/prepaid-billing-cycle-18x5.webp 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Les forfaits mobiles pr\u00e9pay\u00e9s sont souvent propos\u00e9s par <a href=\"https:\/\/tridenstechnology.com\/mvno-mobile-virtual-network-operators\/\">MVNO (<em>op\u00e9rateurs de r\u00e9seaux mobiles virtuels<\/em>)<\/a>qui louent l'infrastructure des principaux ORM (<em>les op\u00e9rateurs de r\u00e9seaux mobiles<\/em>) comme Verizon, AT&amp;T et T-Mobile aux \u00c9tats-Unis.<\/p>\n\n\n\n<p>Cette configuration permet souvent d'obtenir des options moins ch\u00e8res sans avoir \u00e0 se soucier de l'installation de l'appareil ou des frais suppl\u00e9mentaires.<\/p>\n\n\n\n<p>Vous voulez conna\u00eetre la diff\u00e9rence entre les MVNO et les MNO ? Vous trouverez ici une comparaison d\u00e9taill\u00e9e : <a href=\"https:\/\/tridenstechnology.com\/mno-vs-mvno\/\">MNO ou MVNO : quelle est la diff\u00e9rence ?<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-what-is-a-prepaid-mobile-phone\">Qu'est-ce qu'un t\u00e9l\u00e9phone portable pr\u00e9pay\u00e9 ?<\/h2>\n\n\n\n<p>Le terme <em>pr\u00e9pay\u00e9<\/em> s'applique \u00e9galement aux appareils mobiles.<\/p>\n\n\n\n<p>Les t\u00e9l\u00e9phones mobiles pr\u00e9pay\u00e9s, \u00e9galement connus sous le nom de <em>t\u00e9l\u00e9phones \u00e0 br\u00fbleur<\/em> ou <em>go-phones<\/em>sont des appareils mobiles que vous achetez sans contrat, en payant le prix total \u00e0 l'avance.<\/p>\n\n\n\n<p>Les contrats de t\u00e9l\u00e9phonie mobile sont un \u00e9l\u00e9ment essentiel de la vie d'une entreprise. <a href=\"https:\/\/tridenstechnology.com\/postpaid-mobile-plan\/\">plans mobiles postpay\u00e9s<\/a>Les forfaits de t\u00e9l\u00e9phonie mobile pr\u00e9pay\u00e9s \u00e9vitent g\u00e9n\u00e9ralement les contrats d'utilisation de l'appareil.<\/p>\n\n\n\n<p>Cependant, ils proposent des offres telles que des r\u00e9ductions pour plusieurs lignes et des offres sp\u00e9ciales pour l'utilisation de plusieurs services de t\u00e9l\u00e9communications (ligne fixe, internet, sans fil).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-who-are-prepaid-mobile-plans-best-for\">\u00c0 qui s'adressent les forfaits mobiles pr\u00e9pay\u00e9s ?<\/h2>\n\n\n\n<p>Un plan de t\u00e9l\u00e9phonie mobile pr\u00e9pay\u00e9 est le choix id\u00e9al pour les personnes qui pr\u00e9f\u00e8rent mieux contr\u00f4ler leur budget ou qui cherchent \u00e0 r\u00e9duire le co\u00fbt de leur facture de t\u00e9l\u00e9phonie mobile.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"172\" src=\"https:\/\/tridenstechnology.com\/wp-content\/uploads\/prepaid-plan-users-1.webp\" alt=\"Une infographie pr\u00e9sentant les trois principaux groupes d\u00e9mographiques cibles des forfaits mobiles pr\u00e9pay\u00e9s. De gauche \u00e0 droite, on peut voir une repr\u00e9sentation artistique en forme de b\u00e2ton des trois principaux groupes : les enfants, les personnes \u00e2g\u00e9es et les voyageurs.\" class=\"wp-image-42835\" srcset=\"https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/prepaid-plan-users-1.webp 1024w, https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/prepaid-plan-users-1-300x50.webp 300w, https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/prepaid-plan-users-1-768x129.webp 768w, https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/prepaid-plan-users-1-18x3.webp 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-prepaid-plans-for-kids\">Plans pr\u00e9pay\u00e9s pour les enfants<\/h3>\n\n\n\n<p>Un forfait mobile pr\u00e9pay\u00e9 est id\u00e9al pour les enfants.<\/p>\n\n\n\n<p>Les parents peuvent contr\u00f4ler le co\u00fbt de l'achat d'un t\u00e9l\u00e9phone portable pour leurs enfants.<\/p>\n\n\n\n<p>C'est utile lorsqu'il s'agit du premier t\u00e9l\u00e9phone de votre enfant et qu'il n'a pas encore d\u00e9montr\u00e9 sa capacit\u00e9 \u00e0 l'utiliser de mani\u00e8re responsable.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-prepaid-plans-for-seniors\">Plans pr\u00e9pay\u00e9s pour les personnes \u00e2g\u00e9es<\/h3>\n\n\n\n<p>Les personnes \u00e2g\u00e9es n'ont peut-\u00eatre pas besoin d'un forfait t\u00e9l\u00e9phonique tout compris, car elles n'utilisent souvent leur appareil mobile que pour les appels et les SMS.<\/p>\n\n\n\n<p>Ils n'ont pas besoin de beaucoup de donn\u00e9es et peuvent donc se contenter d'un simple forfait pr\u00e9pay\u00e9, ou m\u00eame d'une carte de cr\u00e9dit. <em>pay-as-you-go<\/em> plan.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-prepaid-plans-for-travelers-and-expats\">Plans pr\u00e9pay\u00e9s pour les voyageurs et les expatri\u00e9s<\/h3>\n\n\n\n<p>Les voyageurs et les expatri\u00e9s ont souvent besoin de services mobiles temporaires et flexibles, sans engagement \u00e0 long terme.<\/p>\n\n\n\n<p>Les plans pr\u00e9pay\u00e9s permettent justement de contr\u00f4ler totalement les d\u00e9penses li\u00e9es \u00e0 la t\u00e9l\u00e9phonie mobile.<\/p>\n\n\n\n<p>C'est aussi un moyen facile d'\u00e9viter les frais d'itin\u00e9rance \u00e9lev\u00e9s en changeant facilement de fournisseur en cours de route.<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group key-notes\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p><em>Vous ne savez toujours pas si les forfaits mobiles pr\u00e9pay\u00e9s sont faits pour vous ? Consultez notre comparaison d\u00e9taill\u00e9e des <a href=\"https:\/\/tridenstechnology.com\/postpaid-vs-prepaid\/\">les plans de t\u00e9l\u00e9phonie mobile pr\u00e9pay\u00e9s ou postpay\u00e9s.<\/a><\/em><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-common-deals-and-offers\">Offres courantes<\/h2>\n\n\n\n<p>Les plans de t\u00e9l\u00e9phonie mobile pr\u00e9pay\u00e9s impliquent le paiement \u00e0 l'avance d'un forfait mensuel (ou annuel). <strong>paquet<\/strong> de donn\u00e9es, de textes et de minutes, les services non utilis\u00e9s expirant \u00e0 la fin de la p\u00e9riode.<\/p>\n\n\n\n<p>En revanche, les syst\u00e8mes PAYG (<em>pay-as-you-go<\/em>) sont factur\u00e9s sur la base de <strong>utilisation r\u00e9elle<\/strong>offrant ainsi plus de flexibilit\u00e9 et moins de gaspillage.<\/p>\n\n\n\n<p>Les forfaits PAYG ont un tarif pr\u00e9d\u00e9fini pour les minutes, les textes et les Go ou Mo de donn\u00e9es.<\/p>\n\n\n\n<p>Le PAYG est un sous-ensemble de plans pr\u00e9pay\u00e9s avec une <a href=\"https:\/\/tridenstechnology.com\/usage-based-billing\/\">facturation bas\u00e9e sur l'utilisation<\/a> et une validit\u00e9 plus longue pour les services non utilis\u00e9s - <em>mais<\/em>Avant de prendre une d\u00e9cision, essayez de calculer le co\u00fbt des services par unit\u00e9.<\/p>\n\n\n\n<p>Voici un exemple d'offre de forfaits pr\u00e9pay\u00e9s et de plans PAYG :<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"300\" src=\"https:\/\/tridenstechnology.com\/wp-content\/uploads\/prepaid-plan-offers.webp\" alt=\"Infographie pr\u00e9sentant les diff\u00e9rents types d&#039;offres de forfaits mobiles pr\u00e9pay\u00e9s. L&#039;image pr\u00e9sente trois types de forfaits mobiles pr\u00e9pay\u00e9s : le forfait \u00e0 l&#039;utilisation avec un co\u00fbt fixe par appel, texte et gigaoctet de donn\u00e9es, un forfait mensuel pr\u00e9pay\u00e9 avec un nombre pr\u00e9d\u00e9fini d&#039;appels, de textes et de donn\u00e9es, et un forfait annuel pr\u00e9pay\u00e9 avec un nombre pr\u00e9d\u00e9fini de services mobiles.\" class=\"wp-image-42824\" srcset=\"https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/prepaid-plan-offers.webp 1024w, https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/prepaid-plan-offers-300x88.webp 300w, https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/prepaid-plan-offers-768x225.webp 768w, https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/prepaid-plan-offers-18x5.webp 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Nous avons d\u00e9j\u00e0 mentionn\u00e9 que <a href=\"https:\/\/tridenstechnology.com\/mvno-mobile-virtual-network-operators\/\">MVNO<\/a> sont les meilleurs lorsqu'il s'agit de plans pr\u00e9pay\u00e9s.<\/p>\n\n\n\n<p>Vous voulez savoir quelles grandes soci\u00e9t\u00e9s MVNO proposent les meilleures offres dans votre pays ou votre r\u00e9gion ? Jetez un coup d'\u0153il : <a href=\"https:\/\/tridenstechnology.com\/best-mvno-list\/\">Les meilleurs MVNO et forfaits mobiles par pays : Liste ultime (2024)<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-market-analysis\">Analyse du march\u00e9<\/h2>\n\n\n\n<p>En 2018, environ <a href=\"https:\/\/www.statista.com\/statistics\/566259\/us-types-of-mobile-phone-plans-owned\/\" target=\"_blank\" rel=\"noreferrer noopener\">31.13% d'utilisateurs de t\u00e9l\u00e9phones mobiles aux \u00c9tats-Unis<\/a> utilisaient des services mobiles pr\u00e9pay\u00e9s. Depuis lors, la demande de plans de donn\u00e9es illimit\u00e9es a entra\u00een\u00e9 une baisse significative du nombre d'utilisateurs de services pr\u00e9pay\u00e9s.<\/p>\n\n\n\n<p>Les donn\u00e9es de mars 2024 montrent que 45% des utilisateurs am\u00e9ricains de t\u00e9l\u00e9phones mobiles utilisent des forfaits de donn\u00e9es illimit\u00e9es.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/tridenstechnology.com\/wp-content\/uploads\/most-common-mobile-data-plans-in-the-us.webp\" alt=\"Graphique pr\u00e9sentant le pourcentage des forfaits de donn\u00e9es mobiles les plus couramment utilis\u00e9s aux \u00c9tats-Unis. Les donn\u00e9es datent de mars 2024, et l&#039;on constate que les forfaits de donn\u00e9es illimit\u00e9es sont utilis\u00e9s par 45% des citoyens am\u00e9ricains.\" class=\"wp-image-42825\" srcset=\"https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/most-common-mobile-data-plans-in-the-us.webp 1024w, https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/most-common-mobile-data-plans-in-the-us-300x225.webp 300w, https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/most-common-mobile-data-plans-in-the-us-768x576.webp 768w, https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/most-common-mobile-data-plans-in-the-us-16x12.webp 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Toutefois, d'autres \u00e9tudes indiquent que 56% des utilisateurs de donn\u00e9es illimit\u00e9es aux \u00c9tats-Unis pourraient <a href=\"https:\/\/www.itsworthmore.com\/blog\/post\/how-much-data-do-you-need\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">\u00e9conomisez jusqu'\u00e0 $268.44 par an<\/a> en passant \u00e0 des forfaits pr\u00e9pay\u00e9s ou \u00e0 des forfaits mobiles avec un plafond de donn\u00e9es.<\/p>\n\n\n\n<p>Pour approfondir cette question, examinons le revenu moyen par utilisateur d'un grand ORM (<em>op\u00e9rateur de r\u00e9seau mobile<\/em>) aux \u00c9tats-Unis, T-Mobile.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/tridenstechnology.com\/wp-content\/uploads\/arpu-of-tmobile-postpaid-prepaid-customers-in-the-us.webp\" alt=\"Un graphique pr\u00e9sentant le revenu moyen par utilisateur d&#039;un important ORM aux \u00c9tats-Unis - T-Mobile. Le graphique contient des donn\u00e9es trimestrielles allant du 1er trimestre 2013 au 1er trimestre 2024. Nous pouvons en d\u00e9duire que le revenu moyen par utilisateur est inf\u00e9rieur de plus de $10 pour les forfaits mobiles pr\u00e9pay\u00e9s.\" class=\"wp-image-42826\" srcset=\"https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/arpu-of-tmobile-postpaid-prepaid-customers-in-the-us.webp 1024w, https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/arpu-of-tmobile-postpaid-prepaid-customers-in-the-us-300x225.webp 300w, https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/arpu-of-tmobile-postpaid-prepaid-customers-in-the-us-768x576.webp 768w, https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/arpu-of-tmobile-postpaid-prepaid-customers-in-the-us-16x12.webp 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Au premier trimestre 2024, T-Mobile a g\u00e9n\u00e9r\u00e9 un revenu moyen de $37.18 par utilisateur de t\u00e9l\u00e9phone pr\u00e9pay\u00e9 aux \u00c9tats-Unis.<\/p>\n\n\n\n<p>Ce chiffre est inf\u00e9rieur de $11,61 au revenu moyen des clients postpay\u00e9s, qui \u00e9tait de $48,79.<\/p>\n\n\n\n<p>Les op\u00e9rateurs de t\u00e9l\u00e9phonie mobile tentent de combler le foss\u00e9 entre les utilisateurs de services pr\u00e9pay\u00e9s et postpay\u00e9s en introduisant des plans de donn\u00e9es pr\u00e9pay\u00e9es illimit\u00e9es.<\/p>\n\n\n\n<p>Ils peuvent pr\u00e9senter certaines limitations telles que la d\u00e9priorisation et l'impossibilit\u00e9 d'utiliser vos donn\u00e9es comme un hotspot, mais tout d\u00e9pend de l'op\u00e9rateur.<\/p>\n\n\n\n<p>Il est r\u00e9jouissant de constater que les entreprises commencent \u00e0 proposer des forfaits mobiles illimit\u00e9s sans contrat, offrant ainsi davantage d'options aux consommateurs mobiles.<\/p>\n\n\n<div id=\"polls-44\" class=\"wp-polls\">\n\t<form id=\"polls_form_44\" class=\"wp-polls-form\" action=\"\/index.php\" method=\"post\" data-trp-original-action=\"\/index.php\">\n\t\t<p style=\"display: none;\"><input type=\"hidden\" id=\"poll_44_nonce\" name=\"wp-polls-nonce\" value=\"dca620c867\" \/><\/p>\n\t\t<p style=\"display: none;\"><input type=\"hidden\" name=\"poll_id\" value=\"44\" \/><\/p>\n\t\t<p style=\"text-align: center;\"><strong>Avez-vous d\u00e9j\u00e0 rencontr\u00e9 des probl\u00e8mes de service avec un plan de t\u00e9l\u00e9phonie mobile pr\u00e9pay\u00e9 ?<\/strong><\/p><div id=\"polls-44-ans\" class=\"wp-polls-ans\"><ul class=\"wp-polls-ul\">\n\t\t<li><input type=\"radio\" id=\"poll-answer-150\" name=\"poll_44\" value=\"150\" \/> <label for=\"poll-answer-150\">Oui, fr\u00e9quemment<\/label><\/li>\n\t\t<li><input type=\"radio\" id=\"poll-answer-151\" name=\"poll_44\" value=\"151\" \/> <label for=\"poll-answer-151\">Oui, occasionnellement<\/label><\/li>\n\t\t<li><input type=\"radio\" id=\"poll-answer-152\" name=\"poll_44\" value=\"152\" \/> <label for=\"poll-answer-152\">Non, jamais<\/label><\/li>\n\t\t<li><input type=\"radio\" id=\"poll-answer-153\" name=\"poll_44\" value=\"153\" \/> <label for=\"poll-answer-153\">Je n'utilise pas de forfait mobile pr\u00e9pay\u00e9<\/label><\/li>\n\t\t<\/ul><p style=\"text-align: center;\"><input type=\"button\" name=\"vote\" value=\"   Vote   \" class=\"Buttons\" onclick=\"poll_vote(44);\" \/><\/p><p style=\"text-align: center;\"><a href=\"#ViewPollResults\" onclick=\"poll_result(44); return false;\" title=\"Voir les r\u00e9sultats de ce sondage\">Voir les r\u00e9sultats<\/a><\/p><\/div>\n\t<input type=\"hidden\" name=\"trp-form-language\" value=\"fr\"\/><\/form>\n<\/div>\n<div id=\"polls-44-loading\" class=\"wp-polls-loading\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/tridenstechnology.com\/wp-content\/plugins\/wp-polls\/images\/loading.gif\" width=\"16\" height=\"16\" alt=\"Chargement ...\" title=\"Chargement ...\" class=\"wp-polls-image\" \/>&nbsp;Chargement ...<\/div>\n\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-how-prepaid-billing-works\">Comment fonctionne la facturation pr\u00e9pay\u00e9e ?<\/h2>\n\n\n\n<p>Passons en revue les \u00e9tapes de la facturation pr\u00e9pay\u00e9e :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Utilisation :<\/strong> Lorsque l'utilisateur utilise des services mobiles, la passerelle pr\u00e9pay\u00e9e enregistre le montant des services utilis\u00e9s et les informations relatives au compte de l'utilisateur.<\/li>\n\n\n\n<li><strong>Authentification :<\/strong> La passerelle de paiement authentifie l'utilisateur en envoyant des informations au syst\u00e8me de facturation en temps r\u00e9el.<\/li>\n\n\n\n<li><strong>Informations sur le solde :<\/strong> Le syst\u00e8me de facturation en temps r\u00e9el r\u00e9pond avec les informations sur le solde de l'utilisateur, notifiant \u00e0 la passerelle pr\u00e9pay\u00e9e le solde pr\u00e9pay\u00e9 restant de l'utilisateur.<\/li>\n\n\n\n<li><strong>Montant utilis\u00e9 :<\/strong> La passerelle pr\u00e9pay\u00e9e enregistre le montant des services utilis\u00e9s et le transmet au syst\u00e8me de facturation en temps r\u00e9el.<\/li>\n\n\n\n<li><strong>Mise \u00e0 jour du bilan :<\/strong> Le syst\u00e8me de facturation en temps r\u00e9el recalcule le solde pr\u00e9pay\u00e9 de l'utilisateur en fonction de la quantit\u00e9 de services utilis\u00e9s.<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1025\" height=\"300\" src=\"https:\/\/tridenstechnology.com\/wp-content\/uploads\/prepaid-mobile-billing.webp\" alt=\"Une infographie d\u00e9crivant pr\u00e9cis\u00e9ment le fonctionnement d&#039;un syst\u00e8me de facturation pour les t\u00e9l\u00e9communications avec des forfaits mobiles pr\u00e9pay\u00e9s. L&#039;infographie montre le flux de facturation depuis l&#039;utilisation et l&#039;authentification du mobile par l&#039;utilisateur, jusqu&#039;\u00e0 la soustraction du solde utilis\u00e9 de son solde total.\" class=\"wp-image-42830\" srcset=\"https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/prepaid-mobile-billing.webp 1025w, https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/prepaid-mobile-billing-300x88.webp 300w, https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/prepaid-mobile-billing-768x225.webp 768w, https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/prepaid-mobile-billing-18x5.webp 18w\" sizes=\"(max-width: 1025px) 100vw, 1025px\" \/><\/figure>\n\n\n\n<p class=\"has-text-color has-link-color wp-elements-c6d4fc6c980e7e4dcbbc42a5da4267b9\" style=\"color:#171c46;font-size:30px\"><strong>Transformez votre processus de facturation avec Tridens<\/strong><\/p>\n\n\n\n<p>Derri\u00e8re chaque grande entreprise de t\u00e9l\u00e9communications se cache un syst\u00e8me complexe de facturation en temps r\u00e9el.<\/p>\n\n\n\n<p>Vous \u00eates \u00e0 la recherche d'une solution puissante pour g\u00e9rer diff\u00e9rents forfaits mobiles, du pr\u00e9pay\u00e9 au postpay\u00e9 et au-del\u00e0 ?<\/p>\n\n\n\n<p>Vous souhaitez simplifier vos op\u00e9rations de facturation des t\u00e9l\u00e9communications ?<\/p>\n\n\n\n<p>Faites passer votre exp\u00e9rience de la facturation au niveau sup\u00e9rieur avec <a href=\"https:\/\/tridenstechnology.com\/communications\/\">Tridens Monetization pour les t\u00e9l\u00e9communications<\/a> et rationalisez vos processus comme jamais auparavant.<\/p>\n\n\n\n<div class=\"wp-block-group questions\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"has-text-color has-link-color wp-elements-0bd84266bd65abcc28b5378fd034c88c\" style=\"color:#171c46;font-size:30px\"><strong>FAQ<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group questions\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1693312350036\"><strong class=\"schema-faq-question\">Qu'est-ce qu'un forfait mobile pr\u00e9pay\u00e9 ?<\/strong> <p class=\"schema-faq-answer\">Les forfaits mobiles pr\u00e9pay\u00e9s sont des services pour lesquels vous payez \u00e0 l'avance un certain nombre d'appels, de SMS et de donn\u00e9es. Vous utilisez les services jusqu'\u00e0 ce que le solde soit \u00e9puis\u00e9, puis vous devez recharger pour continuer \u00e0 utiliser le service.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1693312489523\"><strong class=\"schema-faq-question\">Comment fonctionne la facturation avec un forfait mobile pr\u00e9pay\u00e9 ?<\/strong> <p class=\"schema-faq-answer\">La facturation des plans de t\u00e9l\u00e9phonie mobile pr\u00e9pay\u00e9s implique le paiement \u00e0 l'avance d'un ensemble sp\u00e9cifique de services. Au fur et \u00e0 mesure que vous utilisez les services, le syst\u00e8me pr\u00e9pay\u00e9 d\u00e9duit la consommation de votre solde. Une fois le solde \u00e9puis\u00e9, vous devez le recharger pour continuer \u00e0 utiliser les services.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1693312704681\"><strong class=\"schema-faq-question\">Quels sont les avantages des forfaits mobiles pr\u00e9pay\u00e9s ?<\/strong> <p class=\"schema-faq-answer\">Les plans de t\u00e9l\u00e9phonie mobile pr\u00e9pay\u00e9s offrent plusieurs avantages, tels que la ma\u00eetrise des co\u00fbts, l'absence de contrats \u00e0 long terme, la flexibilit\u00e9, l'absence de contr\u00f4le de solvabilit\u00e9, etc.<\/p> <\/div> <\/div>\n\n\n\n<p><\/p>\n<\/div><\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Un guide complet des forfaits mobiles pr\u00e9pay\u00e9s. D\u00e9couvrez les forfaits mobiles pr\u00e9pay\u00e9s et les tendances du march\u00e9 dans l'industrie des t\u00e9l\u00e9communications.<\/p>","protected":false},"author":23,"featured_media":42844,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3440],"tags":[],"class_list":["post-42817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communications","category-3440","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>How Does a Prepaid Mobile Phone Plan Work?<\/title>\n<meta name=\"description\" content=\"A complete guide to prepaid mobile plans. Explore prepaid mobile packages and trending market dynamics in the telecom industry.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tridenstechnology.com\/fr\/plan-mobile-prepaye\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prepaid Mobile Plans: How Do They Work?\" \/>\n<meta property=\"og:description\" content=\"A complete guide to prepaid mobile plans. Explore prepaid mobile packages and trending market dynamics in the telecom industry.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tridenstechnology.com\/fr\/plan-mobile-prepaye\/\" \/>\n<meta property=\"og:site_name\" content=\"Tridens\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tridenstechnology\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-01T13:12:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-06T13:38:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/prepaid-mobile-plan.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"497\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"\u017dan Kelbi\u010d\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TridensTech\" \/>\n<meta name=\"twitter:site\" content=\"@TridensTech\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u017dan Kelbi\u010d\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Comment fonctionne un plan de t\u00e9l\u00e9phonie mobile pr\u00e9pay\u00e9 ?","description":"Un guide complet des forfaits mobiles pr\u00e9pay\u00e9s. D\u00e9couvrez les forfaits mobiles pr\u00e9pay\u00e9s et les tendances du march\u00e9 dans l'industrie des t\u00e9l\u00e9communications.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tridenstechnology.com\/fr\/plan-mobile-prepaye\/","og_locale":"fr_FR","og_type":"article","og_title":"Prepaid Mobile Plans: How Do They Work?","og_description":"A complete guide to prepaid mobile plans. Explore prepaid mobile packages and trending market dynamics in the telecom industry.","og_url":"https:\/\/tridenstechnology.com\/fr\/plan-mobile-prepaye\/","og_site_name":"Tridens","article_publisher":"https:\/\/www.facebook.com\/tridenstechnology","article_published_time":"2024-07-01T13:12:15+00:00","article_modified_time":"2025-02-06T13:38:00+00:00","og_image":[{"width":1024,"height":497,"url":"https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/prepaid-mobile-plan.webp","type":"image\/webp"}],"author":"\u017dan Kelbi\u010d","twitter_card":"summary_large_image","twitter_creator":"@TridensTech","twitter_site":"@TridensTech","twitter_misc":{"\u00c9crit par":"\u017dan Kelbi\u010d","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tridenstechnology.com\/prepaid-mobile-plan\/#article","isPartOf":{"@id":"https:\/\/tridenstechnology.com\/prepaid-mobile-plan\/"},"author":{"name":"\u017dan Kelbi\u010d","@id":"https:\/\/tridenstechnology.com\/#\/schema\/person\/37020c53e664a4cc2286c94524e47d3b"},"headline":"Prepaid Mobile Plans: How Do They Work?","datePublished":"2024-07-01T13:12:15+00:00","dateModified":"2025-02-06T13:38:00+00:00","mainEntityOfPage":{"@id":"https:\/\/tridenstechnology.com\/prepaid-mobile-plan\/"},"wordCount":1210,"commentCount":0,"publisher":{"@id":"https:\/\/tridenstechnology.com\/#organization"},"image":{"@id":"https:\/\/tridenstechnology.com\/prepaid-mobile-plan\/#primaryimage"},"thumbnailUrl":"https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/prepaid-mobile-plan.webp","articleSection":["Communications"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tridenstechnology.com\/prepaid-mobile-plan\/#respond"]}],"accessibilityFeature":["tableOfContents"]},{"@type":["WebPage","FAQPage"],"@id":"https:\/\/tridenstechnology.com\/prepaid-mobile-plan\/","url":"https:\/\/tridenstechnology.com\/prepaid-mobile-plan\/","name":"Comment fonctionne un plan de t\u00e9l\u00e9phonie mobile pr\u00e9pay\u00e9 ?","isPartOf":{"@id":"https:\/\/tridenstechnology.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tridenstechnology.com\/prepaid-mobile-plan\/#primaryimage"},"image":{"@id":"https:\/\/tridenstechnology.com\/prepaid-mobile-plan\/#primaryimage"},"thumbnailUrl":"https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/prepaid-mobile-plan.webp","datePublished":"2024-07-01T13:12:15+00:00","dateModified":"2025-02-06T13:38:00+00:00","description":"Un guide complet des forfaits mobiles pr\u00e9pay\u00e9s. D\u00e9couvrez les forfaits mobiles pr\u00e9pay\u00e9s et les tendances du march\u00e9 dans l'industrie des t\u00e9l\u00e9communications.","breadcrumb":{"@id":"https:\/\/tridenstechnology.com\/prepaid-mobile-plan\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/tridenstechnology.com\/prepaid-mobile-plan\/#faq-question-1693312350036"},{"@id":"https:\/\/tridenstechnology.com\/prepaid-mobile-plan\/#faq-question-1693312489523"},{"@id":"https:\/\/tridenstechnology.com\/prepaid-mobile-plan\/#faq-question-1693312704681"}],"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tridenstechnology.com\/prepaid-mobile-plan\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/tridenstechnology.com\/prepaid-mobile-plan\/#primaryimage","url":"https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/prepaid-mobile-plan.webp","contentUrl":"https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/prepaid-mobile-plan.webp","width":1024,"height":497,"caption":"A heading blog image for a Prepaid Mobile Plans blog, that visually represents the key aspects of prepaid mobile plans, such as time of billing, use of SIM cards and mobile recharging of balance. These aspects are represented with a calendar that marks important events of prepaid mobile plans' lifecycle, a physical SIM card which has an engraved globe on it - representing global travel, and a smartphone with a storefront, that prompts the user to recharge their prepaid balance."},{"@type":"BreadcrumbList","@id":"https:\/\/tridenstechnology.com\/prepaid-mobile-plan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tridenstechnology.com\/"},{"@type":"ListItem","position":2,"name":"Prepaid Mobile Plans: How Do They Work?"}]},{"@type":"WebSite","@id":"https:\/\/tridenstechnology.com\/#website","url":"https:\/\/tridenstechnology.com\/","name":"Tridens","description":"Mon\u00e9tisation, facturation et recharge des v\u00e9hicules \u00e9lectriques","publisher":{"@id":"https:\/\/tridenstechnology.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tridenstechnology.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/tridenstechnology.com\/#organization","name":"Tridens","url":"https:\/\/tridenstechnology.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/tridenstechnology.com\/#\/schema\/logo\/image\/","url":"https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/2019\/02\/tridens_logo_invert.png","contentUrl":"https:\/\/d2xqcz296oofyv.cloudfront.net\/wp-content\/uploads\/2019\/02\/tridens_logo_invert.png","width":600,"height":191,"caption":"Tridens"},"image":{"@id":"https:\/\/tridenstechnology.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tridenstechnology","https:\/\/x.com\/TridensTech","https:\/\/www.instagram.com\/tridenstechnology\/","https:\/\/www.linkedin.com\/company\/tridens","https:\/\/www.youtube.com\/user\/TridensIT"]},{"@type":"Person","@id":"https:\/\/tridenstechnology.com\/#\/schema\/person\/37020c53e664a4cc2286c94524e47d3b","name":"\u017dan Kelbi\u010d","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3a330b9cf982a01ff951d3cf06716fc200532267fb8c1733dec54224511567c4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3a330b9cf982a01ff951d3cf06716fc200532267fb8c1733dec54224511567c4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3a330b9cf982a01ff951d3cf06716fc200532267fb8c1733dec54224511567c4?s=96&d=mm&r=g","caption":"\u017dan Kelbi\u010d"},"description":"\u017dan Kelbi\u010d est un sp\u00e9cialiste du marketing num\u00e9rique qui combine sa formation en programmation avec un amour pour l'\u00e9criture et la conception visuelle. Il est toujours \u00e0 l'aff\u00fbt des nouvelles tendances technologiques, telles que l'IA, l'informatique mobile et les technologies informatiques de pointe.","url":"https:\/\/tridenstechnology.com\/fr\/author\/zan-kelbictridenstechnology-com\/"},{"@type":"Question","@id":"https:\/\/tridenstechnology.com\/prepaid-mobile-plan\/#faq-question-1693312350036","position":1,"url":"https:\/\/tridenstechnology.com\/prepaid-mobile-plan\/#faq-question-1693312350036","name":"Qu'est-ce qu'un forfait mobile pr\u00e9pay\u00e9 ?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Prepaid mobile plans are services where you pay in advance for a set amount of calls, texts and data. You use the services until the balance is depleted, and then you need to top up or recharge to continue using the service.","inLanguage":"fr-FR"},"inLanguage":"fr-FR"},{"@type":"Question","@id":"https:\/\/tridenstechnology.com\/prepaid-mobile-plan\/#faq-question-1693312489523","position":2,"url":"https:\/\/tridenstechnology.com\/prepaid-mobile-plan\/#faq-question-1693312489523","name":"Comment fonctionne la facturation avec un forfait mobile pr\u00e9pay\u00e9 ?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Billing for prepaid mobile plans involves paying upfront for a specific package of services. As you use the services, the prepaid system subtracts the usage from your balance. Once the balance is used up, you need to top up to keep using the services.","inLanguage":"fr-FR"},"inLanguage":"fr-FR"},{"@type":"Question","@id":"https:\/\/tridenstechnology.com\/prepaid-mobile-plan\/#faq-question-1693312704681","position":3,"url":"https:\/\/tridenstechnology.com\/prepaid-mobile-plan\/#faq-question-1693312704681","name":"Quels sont les avantages des forfaits mobiles pr\u00e9pay\u00e9s ?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"Prepaid mobile plans offer several advantages, such as: cost control, no long-term contracts, flexibility, no credit checks, etc.","inLanguage":"fr-FR"},"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/tridenstechnology.com\/fr\/wp-json\/wp\/v2\/posts\/42817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tridenstechnology.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tridenstechnology.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tridenstechnology.com\/fr\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/tridenstechnology.com\/fr\/wp-json\/wp\/v2\/comments?post=42817"}],"version-history":[{"count":0,"href":"https:\/\/tridenstechnology.com\/fr\/wp-json\/wp\/v2\/posts\/42817\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tridenstechnology.com\/fr\/wp-json\/wp\/v2\/media\/42844"}],"wp:attachment":[{"href":"https:\/\/tridenstechnology.com\/fr\/wp-json\/wp\/v2\/media?parent=42817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tridenstechnology.com\/fr\/wp-json\/wp\/v2\/categories?post=42817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tridenstechnology.com\/fr\/wp-json\/wp\/v2\/tags?post=42817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}